{"id":14152,"date":"2022-05-10T12:42:26","date_gmt":"2022-05-10T09:42:26","guid":{"rendered":"https:\/\/masterchem.fi\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/"},"modified":"2022-05-10T12:42:26","modified_gmt":"2022-05-10T09:42:26","slug":"sodium-metasilicate-pentahydrate-cas-10213-79-3","status":"publish","type":"product","link":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/","title":{"rendered":"Sodium metasilicate pentahydrate (CAS 10213-79-3)"},"content":{"rendered":"<p><strong>Information<\/strong><\/p>\n<p>Industries: Household chemicals, Building chemistry<br \/>\nCAS number: 10213-79-3<br \/>\nWE number: 600-279-4<br \/>\nChemical formula: H2O3Si\u00b72Na\u00b75H2O<\/p>\n<p><strong>Other physical properties<\/strong><\/p>\n<p>Melting \/ freezing point: 1089\u00b0C<br \/>\nSolubility in water: 210 g\/l (20\u00b0C)<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Sodium metasilicate pentahydrate (CAS 10213-79-3)<\/strong><\/p>\n<p>Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions. It is an ionic compound consisting of sodium cations Na+ and the polymeric metasilicate anions [\u2013SiO2\u22123\u2013]n. It is a colorless crystalline hygroscopic and deliquescent solid, soluble in water (giving an alkaline solution) but not in alcohols.<\/p>\n","protected":false},"featured_media":14153,"template":"","meta":[],"product_brand":[],"product_cat":[199,209,202],"product_tag":[],"class_list":{"0":"post-14152","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-all-products","7":"product_cat-construction-industry","8":"product_cat-household-chemicals","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable","16":"rtwpvg-product"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sodium metasilicate pentahydrate (CAS 10213-79-3) - MasterChem | kemikaalien tuotanto ja myynti<\/title>\n<meta name=\"description\" content=\"Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sodium metasilicate pentahydrate (CAS 10213-79-3) - MasterChem | kemikaalien tuotanto ja myynti\" \/>\n<meta property=\"og:description\" content=\"Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/\" \/>\n<meta property=\"og:site_name\" content=\"MasterChem | kemikaalien tuotanto ja myynti\" \/>\n<meta property=\"og:image\" content=\"https:\/\/masterchem.fi\/wp-content\/uploads\/2022\/05\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/\",\"url\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/\",\"name\":\"Sodium metasilicate pentahydrate (CAS 10213-79-3) - MasterChem | kemikaalien tuotanto ja myynti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/masterchem.fi\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg\",\"datePublished\":\"2022-05-10T09:42:26+00:00\",\"description\":\"Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/masterchem.fi\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg\",\"contentUrl\":\"https:\\\/\\\/masterchem.fi\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Sodium metasilicate pentahydrate (CAS 10213-79-3) 25kg-MasterChem\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/product\\\/sodium-metasilicate-pentahydrate-cas-10213-79-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/masterchem.fi\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sodium metasilicate pentahydrate (CAS 10213-79-3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/\",\"name\":\"MasterChem | kemikaalien tuotanto ja myynti\",\"description\":\"t\u00f6\u00f6stuskemikaalide suurtarnija. Keemiatoodete tootmine.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/masterchem.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sodium metasilicate pentahydrate (CAS 10213-79-3) - MasterChem | kemikaalien tuotanto ja myynti","description":"Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/","og_locale":"en_US","og_type":"article","og_title":"Sodium metasilicate pentahydrate (CAS 10213-79-3) - MasterChem | kemikaalien tuotanto ja myynti","og_description":"Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions.","og_url":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/","og_site_name":"MasterChem | kemikaalien tuotanto ja myynti","og_image":[{"width":1000,"height":1000,"url":"https:\/\/masterchem.fi\/wp-content\/uploads\/2022\/05\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/","url":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/","name":"Sodium metasilicate pentahydrate (CAS 10213-79-3) - MasterChem | kemikaalien tuotanto ja myynti","isPartOf":{"@id":"https:\/\/masterchem.fi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/#primaryimage"},"image":{"@id":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/#primaryimage"},"thumbnailUrl":"https:\/\/masterchem.fi\/wp-content\/uploads\/2022\/05\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg","datePublished":"2022-05-10T09:42:26+00:00","description":"Sodium metasilicate is the chemical substance with formula Na2SiO3, which is the main component of commercial sodium silicate solutions.","breadcrumb":{"@id":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/#primaryimage","url":"https:\/\/masterchem.fi\/wp-content\/uploads\/2022\/05\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg","contentUrl":"https:\/\/masterchem.fi\/wp-content\/uploads\/2022\/05\/Natriummetasilikaattipentahydraatti-CAS-10213-79-3-25kg-MasterChem.jpg","width":1000,"height":1000,"caption":"Sodium metasilicate pentahydrate (CAS 10213-79-3) 25kg-MasterChem"},{"@type":"BreadcrumbList","@id":"https:\/\/masterchem.fi\/en\/product\/sodium-metasilicate-pentahydrate-cas-10213-79-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/masterchem.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/masterchem.fi\/shop\/"},{"@type":"ListItem","position":3,"name":"Sodium metasilicate pentahydrate (CAS 10213-79-3)"}]},{"@type":"WebSite","@id":"https:\/\/masterchem.fi\/en\/#website","url":"https:\/\/masterchem.fi\/en\/","name":"MasterChem | kemikaalien tuotanto ja myynti","description":"t\u00f6\u00f6stuskemikaalide suurtarnija. Keemiatoodete tootmine.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/masterchem.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/product\/14152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/media\/14153"}],"wp:attachment":[{"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/media?parent=14152"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/product_brand?post=14152"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/product_cat?post=14152"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/masterchem.fi\/en\/wp-json\/wp\/v2\/product_tag?post=14152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}